{"id":107,"date":"2021-09-18T08:32:40","date_gmt":"2021-09-18T08:32:40","guid":{"rendered":"https:\/\/max.mast-design.de\/?page_id=107"},"modified":"2022-05-01T12:42:07","modified_gmt":"2022-05-01T12:42:07","slug":"ueber-uns","status":"publish","type":"page","link":"https:\/\/zulassung-krefeld.de\/en\/ueber-uns\/","title":{"rendered":"\u00dcber uns"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"107\" class=\"elementor elementor-107\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5529c61 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5529c61\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-50ef3b2\" data-id=\"50ef3b2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b24696f elementor-widget elementor-widget-image\" data-id=\"b24696f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/zulassung-krefeld.de\/wp-content\/uploads\/2021\/09\/pexels-pixabay-327540.jpg\" class=\"attachment-large size-large wp-image-92\" alt=\"\" srcset=\"https:\/\/zulassung-krefeld.de\/wp-content\/uploads\/2021\/09\/pexels-pixabay-327540.jpg 500w, https:\/\/zulassung-krefeld.de\/wp-content\/uploads\/2021\/09\/pexels-pixabay-327540-300x300.jpg 300w, https:\/\/zulassung-krefeld.de\/wp-content\/uploads\/2021\/09\/pexels-pixabay-327540-150x150.jpg 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-99cd4f3\" data-id=\"99cd4f3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-660ed71 elementor-widget elementor-widget-heading\" data-id=\"660ed71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u00dcber uns<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4cd3c71 elementor-widget elementor-widget-heading\" data-id=\"4cd3c71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00dcber 20 Jahre Erfahrung in der Automobile Welt<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e76ba4 elementor-widget elementor-widget-text-editor\" data-id=\"8e76ba4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wir sind schon \u00fcber 20 Jahre in der Welt des Automobile Zuhause. Als erfahrener Autoh\u00e4ndler habe wir die Schwierigkeiten Erkannt, wenn es um die Autozulassung geht. Daher bieten wir nicht nur unseren bisherigen Kunden unsere Dienstleitungen bei der Zulassungsstelle in Krefeld an.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-db46274 elementor-reverse-tablet elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"db46274\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e667959\" data-id=\"e667959\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0c51c72 elementor-widget elementor-widget-heading\" data-id=\"0c51c72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Erfahre mehr \u00fcber uns<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5c2010 elementor-widget elementor-widget-heading\" data-id=\"c5c2010\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Smartparts24 in Krefeld<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a425fcd elementor-widget elementor-widget-text-editor\" data-id=\"a425fcd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Als Smartparts24 k\u00f6nnen wir seit langen eine gro\u00dfe Vielfalt an Service in Krefeld anbieten. Wir bitten Ihnen um die Marke Smart, rund um alles an. Egal ob Gebrauchtfahrzeuge, Service oder Ersatzteile. Wir k\u00f6nnen Ihnen bei jeden Problem weiter helfen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eea52b9 elementor-widget elementor-widget-button\" data-id=\"eea52b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"https:\/\/smartparts24.de\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Erfahren Sie mehr \u00fcber uns<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-48e2faf\" data-id=\"48e2faf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d51145d elementor-widget elementor-widget-image\" data-id=\"d51145d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"640\" height=\"426\" data-src=\"https:\/\/zulassung-krefeld.de\/wp-content\/uploads\/2021\/09\/smartparts24-ueberuns-1024x681.jpeg\" class=\"attachment-large size-large wp-image-119 lazyload\" alt=\"\" data-srcset=\"https:\/\/zulassung-krefeld.de\/wp-content\/uploads\/2021\/09\/smartparts24-ueberuns-1024x681.jpeg 1024w, https:\/\/zulassung-krefeld.de\/wp-content\/uploads\/2021\/09\/smartparts24-ueberuns-300x200.jpeg 300w, https:\/\/zulassung-krefeld.de\/wp-content\/uploads\/2021\/09\/smartparts24-ueberuns-768x511.jpeg 768w, https:\/\/zulassung-krefeld.de\/wp-content\/uploads\/2021\/09\/smartparts24-ueberuns.jpeg 1200w\" data-sizes=\"(max-width: 640px) 100vw, 640px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 640px; --smush-placeholder-aspect-ratio: 640\/426;\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2e00d6c2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2e00d6c2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5a8a9870\" data-id=\"5a8a9870\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ba13bc6 elementor-cta--layout-image-left elementor-cta--valign-middle elementor-cta--mobile-layout-image-above elementor-cta--skin-classic elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"2ba13bc6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg lazyload\" style=\"background-image:inherit;\" role=\"img\" aria-label=\"DSC_0140\" data-bg-image=\"url(https:\/\/zulassung-krefeld.de\/wp-content\/uploads\/2022\/04\/DSC_0140-1024x681.jpg)\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-cta__image\">\n\t\t\t\t\t\t<img decoding=\"async\" width=\"250\" height=\"55\" data-src=\"https:\/\/zulassung-krefeld.de\/wp-content\/uploads\/2021\/09\/Logo-zulassungkr_light.png\" class=\"attachment-full size-full wp-image-91 lazyload\" alt=\"\" data-sizes=\"(max-width: 34.9rem) calc(100vw - 2rem), (max-width: 53rem) calc(8 * (100vw \/ 12)), (min-width: 53rem) calc(6 * (100vw \/ 12)), 100vw\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 250px; --smush-placeholder-aspect-ratio: 250\/55;\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tIhr Zulassungsdienst f\u00fcr Krefeld\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tSie m\u00f6chten Ihr Fahrzeug Anmelden, Ummelden oder Abmelden. Wir helfen Ihnen weiter. Jetzt ganz einfach online einen Termin vereinbaren.\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-\" href=\"https:\/\/zulassung-krefeld.de\/en\/ueber-uns\/\">\n\t\t\t\t\t\tJetzt Anfragen\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6f8af75 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6f8af75\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-75dd3fd6\" data-id=\"75dd3fd6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-79b34503 elementor-widget elementor-widget-image\" data-id=\"79b34503\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"210\" height=\"46\" data-src=\"https:\/\/zulassung-krefeld.de\/wp-content\/uploads\/2021\/09\/Logo-zulassungkr-2_light.png\" class=\"attachment-large size-large wp-image-37 lazyload\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 210px; --smush-placeholder-aspect-ratio: 210\/46;\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2e0317b\" data-id=\"2e0317b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-47f0ef75 elementor-nav-menu__align-center elementor-nav-menu--dropdown-none elementor-widget elementor-widget-nav-menu\" data-id=\"47f0ef75\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-none\">\n\t\t\t\t<ul id=\"menu-1-47f0ef75\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-307\"><a href=\"https:\/\/zulassung-krefeld.de\/en\/impressum\/\" class=\"elementor-item\">Impressum<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-privacy-policy menu-item-315\"><a rel=\"privacy-policy\" href=\"https:\/\/zulassung-krefeld.de\/en\/datenschutzerklaerung\/\" class=\"elementor-item\">Datenschutz<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-47f0ef75\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-307\"><a href=\"https:\/\/zulassung-krefeld.de\/en\/impressum\/\" class=\"elementor-item\" tabindex=\"-1\">Impressum<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-privacy-policy menu-item-315\"><a rel=\"privacy-policy\" href=\"https:\/\/zulassung-krefeld.de\/en\/datenschutzerklaerung\/\" class=\"elementor-item\" tabindex=\"-1\">Datenschutz<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-462943b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"462943b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-250bf8ab\" data-id=\"250bf8ab\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3179a80c elementor-widget elementor-widget-text-editor\" data-id=\"3179a80c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a9 2020 Zulassung Krefeld bei Smartparts24<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6efb3dd6\" data-id=\"6efb3dd6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-2393d287\" data-id=\"2393d287\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4fe38075 elementor-shape-square e-grid-align-right e-grid-align-mobile-center elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"4fe38075\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-animation-grow elementor-repeater-item-0e23116\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-animation-grow elementor-repeater-item-70a5bbf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-twitter\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-animation-grow elementor-repeater-item-23ea04b\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-youtube\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u00dcber uns \u00dcber 20 Jahre Erfahrung in der Automobile Welt Wir sind schon \u00fcber 20 Jahre in der Welt des Automobile Zuhause. Als erfahrener Autoh\u00e4ndler habe wir die Schwierigkeiten Erkannt, wenn es um die Autozulassung geht. Daher bieten wir nicht nur unseren bisherigen Kunden unsere Dienstleitungen bei der Zulassungsstelle in Krefeld an. Erfahre mehr \u00fcber &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/zulassung-krefeld.de\/en\/ueber-uns\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8222;\u00dcber uns&#8220;<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-107","page","type-page","status-publish","hentry","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00dcber uns - Zulassung Krefeld<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zulassung-krefeld.de\/en\/ueber-uns\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00dcber uns - Zulassung Krefeld\" \/>\n<meta property=\"og:description\" content=\"\u00dcber uns \u00dcber 20 Jahre Erfahrung in der Automobile Welt Wir sind schon \u00fcber 20 Jahre in der Welt des Automobile Zuhause. Als erfahrener Autoh\u00e4ndler habe wir die Schwierigkeiten Erkannt, wenn es um die Autozulassung geht. Daher bieten wir nicht nur unseren bisherigen Kunden unsere Dienstleitungen bei der Zulassungsstelle in Krefeld an. Erfahre mehr \u00fcber &hellip; Continue reading &quot;\u00dcber uns&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zulassung-krefeld.de\/en\/ueber-uns\/\" \/>\n<meta property=\"og:site_name\" content=\"Zulassung Krefeld\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-01T12:42:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zulassung-krefeld.de\/wp-content\/uploads\/2021\/09\/pexels-pixabay-327540.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zulassung-krefeld.de\\\/ueber-uns\\\/\",\"url\":\"https:\\\/\\\/zulassung-krefeld.de\\\/ueber-uns\\\/\",\"name\":\"\u00dcber uns - Zulassung Krefeld\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zulassung-krefeld.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zulassung-krefeld.de\\\/ueber-uns\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zulassung-krefeld.de\\\/ueber-uns\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zulassung-krefeld.de\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/pexels-pixabay-327540.jpg\",\"datePublished\":\"2021-09-18T08:32:40+00:00\",\"dateModified\":\"2022-05-01T12:42:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zulassung-krefeld.de\\\/ueber-uns\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zulassung-krefeld.de\\\/ueber-uns\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zulassung-krefeld.de\\\/ueber-uns\\\/#primaryimage\",\"url\":\"https:\\\/\\\/zulassung-krefeld.de\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/pexels-pixabay-327540.jpg\",\"contentUrl\":\"https:\\\/\\\/zulassung-krefeld.de\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/pexels-pixabay-327540.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zulassung-krefeld.de\\\/ueber-uns\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/zulassung-krefeld.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00dcber uns\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zulassung-krefeld.de\\\/#website\",\"url\":\"https:\\\/\\\/zulassung-krefeld.de\\\/\",\"name\":\"Zulassung Krefeld\",\"description\":\"Schnell &amp; unkompliziert\",\"publisher\":{\"@id\":\"https:\\\/\\\/zulassung-krefeld.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zulassung-krefeld.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zulassung-krefeld.de\\\/#organization\",\"name\":\"Zulassung Krefeld\",\"url\":\"https:\\\/\\\/zulassung-krefeld.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zulassung-krefeld.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zulassung-krefeld.de\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Logo-zulassungkr-2-header-2.png\",\"contentUrl\":\"https:\\\/\\\/zulassung-krefeld.de\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Logo-zulassungkr-2-header-2.png\",\"width\":320,\"height\":71,\"caption\":\"Zulassung Krefeld\"},\"image\":{\"@id\":\"https:\\\/\\\/zulassung-krefeld.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00dcber uns - Zulassung Krefeld","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zulassung-krefeld.de\/en\/ueber-uns\/","og_locale":"en_US","og_type":"article","og_title":"\u00dcber uns - Zulassung Krefeld","og_description":"\u00dcber uns \u00dcber 20 Jahre Erfahrung in der Automobile Welt Wir sind schon \u00fcber 20 Jahre in der Welt des Automobile Zuhause. Als erfahrener Autoh\u00e4ndler habe wir die Schwierigkeiten Erkannt, wenn es um die Autozulassung geht. Daher bieten wir nicht nur unseren bisherigen Kunden unsere Dienstleitungen bei der Zulassungsstelle in Krefeld an. Erfahre mehr \u00fcber &hellip; Continue reading \"\u00dcber uns\"","og_url":"https:\/\/zulassung-krefeld.de\/en\/ueber-uns\/","og_site_name":"Zulassung Krefeld","article_modified_time":"2022-05-01T12:42:07+00:00","og_image":[{"url":"https:\/\/zulassung-krefeld.de\/wp-content\/uploads\/2021\/09\/pexels-pixabay-327540.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/zulassung-krefeld.de\/ueber-uns\/","url":"https:\/\/zulassung-krefeld.de\/ueber-uns\/","name":"\u00dcber uns - Zulassung Krefeld","isPartOf":{"@id":"https:\/\/zulassung-krefeld.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zulassung-krefeld.de\/ueber-uns\/#primaryimage"},"image":{"@id":"https:\/\/zulassung-krefeld.de\/ueber-uns\/#primaryimage"},"thumbnailUrl":"https:\/\/zulassung-krefeld.de\/wp-content\/uploads\/2021\/09\/pexels-pixabay-327540.jpg","datePublished":"2021-09-18T08:32:40+00:00","dateModified":"2022-05-01T12:42:07+00:00","breadcrumb":{"@id":"https:\/\/zulassung-krefeld.de\/ueber-uns\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zulassung-krefeld.de\/ueber-uns\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zulassung-krefeld.de\/ueber-uns\/#primaryimage","url":"https:\/\/zulassung-krefeld.de\/wp-content\/uploads\/2021\/09\/pexels-pixabay-327540.jpg","contentUrl":"https:\/\/zulassung-krefeld.de\/wp-content\/uploads\/2021\/09\/pexels-pixabay-327540.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/zulassung-krefeld.de\/ueber-uns\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/zulassung-krefeld.de\/"},{"@type":"ListItem","position":2,"name":"\u00dcber uns"}]},{"@type":"WebSite","@id":"https:\/\/zulassung-krefeld.de\/#website","url":"https:\/\/zulassung-krefeld.de\/","name":"Zulassung Krefeld","description":"Schnell &amp; unkompliziert","publisher":{"@id":"https:\/\/zulassung-krefeld.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zulassung-krefeld.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/zulassung-krefeld.de\/#organization","name":"Zulassung Krefeld","url":"https:\/\/zulassung-krefeld.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zulassung-krefeld.de\/#\/schema\/logo\/image\/","url":"https:\/\/zulassung-krefeld.de\/wp-content\/uploads\/2021\/09\/Logo-zulassungkr-2-header-2.png","contentUrl":"https:\/\/zulassung-krefeld.de\/wp-content\/uploads\/2021\/09\/Logo-zulassungkr-2-header-2.png","width":320,"height":71,"caption":"Zulassung Krefeld"},"image":{"@id":"https:\/\/zulassung-krefeld.de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/zulassung-krefeld.de\/en\/wp-json\/wp\/v2\/pages\/107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zulassung-krefeld.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/zulassung-krefeld.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/zulassung-krefeld.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zulassung-krefeld.de\/en\/wp-json\/wp\/v2\/comments?post=107"}],"version-history":[{"count":34,"href":"https:\/\/zulassung-krefeld.de\/en\/wp-json\/wp\/v2\/pages\/107\/revisions"}],"predecessor-version":[{"id":553,"href":"https:\/\/zulassung-krefeld.de\/en\/wp-json\/wp\/v2\/pages\/107\/revisions\/553"}],"wp:attachment":[{"href":"https:\/\/zulassung-krefeld.de\/en\/wp-json\/wp\/v2\/media?parent=107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}